{"id":55066,"date":"2024-06-26T07:54:45","date_gmt":"2024-06-26T05:54:45","guid":{"rendered":"https:\/\/relaisgourmet.com\/farandole-de-verduras-y-frutas-con-foie-gras\/"},"modified":"2025-04-12T22:46:47","modified_gmt":"2025-04-12T20:46:47","slug":"farandole-de-verduras-y-frutas-con-foie-gras","status":"publish","type":"post","link":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/","title":{"rendered":"Farandole de verduras y frutas con Foie Gras"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Este plato lleva verduras y foie gras, ofreciendo una experiencia culinaria \u00fanica.<\/p>\n\n<p class=\"wp-block-paragraph\">El foie gras, ingrediente de lujo por excelencia, se invita a una receta ligera y fresca, perfecta para todas tus ocasiones gourmet. Descubre esta refrescante ensalada que combina verduras crujientes y foie gras entero, una armon\u00eda de sabores para disfrutar con tus invitados.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong data-start=\"98\" data-end=\"154\">Tiempo de preparaci\u00f3n: 10 minutos | Para 3 personas<\/strong><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-ingredients\">Ingredientes:<\/h3>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/relaisgourmet.com\/es\/categor&#xED;a-producto\/nuestros-foies-gras\/\">250 g de foie gras entero de calidad  <\/a><\/li>\n\n\n\n<li>1 mel\u00f3n o mango<\/li>\n\n\n\n<li>R\u00e1bano<\/li>\n\n\n\n<li>Tallos de apio<\/li>\n\n\n\n<li>Calabacines amarillos y verdes<\/li>\n\n\n\n<li>Ensalada (a elegir)<\/li>\n\n\n\n<li>Brotes de espinacas<\/li>\n\n\n\n<li>Zanahorias<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-preparation\">Preparaci\u00f3n :<\/h3>\n\n<ol class=\"wp-block-list\">\n<li><p data-start=\"718\" data-end=\"997\"><strong data-start=\"718\" data-end=\"751\">Lavar y preparar las verduras<\/strong>: Empieza por lavar bien todas las verduras. Pela las zanahorias y c\u00f3rtalas en cintas finas con un pelador. Parte los r\u00e1banos en 4 partes iguales y corta los calabacines y los tallos de apio en rodajas grandes.<\/p><\/li>\n\n\n\n<li><p data-start=\"1002\" data-end=\"1192\"><strong data-start=\"1002\" data-end=\"1036\">Prepara el mel\u00f3n<\/strong> o el mango: Utiliza un sacabolas para hacer bolitas de mel\u00f3n o mango. Este toque dulce a\u00f1adir\u00e1 un toque de frescura a tu plato.<\/p><\/li>\n\n\n\n<li><p data-start=\"1197\" data-end=\"1458\"><strong data-start=\"1197\" data-end=\"1218\">Disp\u00f3n la ensalada<\/strong>: Sobre las hojas de ensalada y los brotes de espinacas, coloca finas virutas de foie gras. A continuaci\u00f3n, a\u00f1ade las rodajas de calabac\u00edn y los r\u00e1banos, alternando texturas y sabores para conseguir un efecto visual y gustativo irresistible.<\/p><\/li>\n\n\n\n<li><p data-start=\"1463\" data-end=\"1652\"><strong data-start=\"1463\" data-end=\"1510\">Combina brochetas de fruta y foie<\/strong> gras: En peque\u00f1as brochetas, alterna bolitas de mel\u00f3n o mango con virutas de foie gras para una presentaci\u00f3n elegante y sabrosa.<\/p><\/li>\n\n\n\n<li><p data-start=\"1657\" data-end=\"1794\"><strong data-start=\"1657\" data-end=\"1682\">Enrolla las zanahorias<\/strong>: Enrolla las cintas de zanahoria sobre s\u00ed mismas y suj\u00e9talas con un palito para darles un toque de delicadeza.<\/p><\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\">Esta receta r\u00e1pida y f\u00e1cil es ideal para comidas ligeras o como entrante para una buena cena. El foie gras entero, con su textura que se deshace en la boca, combina perfectamente con verduras crujientes y fruta dulce. Si quieres diversificar tus recetas, <a href=\"https:\/\/relaisgourmet.com\/es\/recetas-de-foie-gras\/\">explora aqu\u00ed otras ideas gastron\u00f3micas.<\/a><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-une-touche-de-luxe-a-votre-table\">Un toque de lujo en tu mesa<\/h3>\n\n<p class=\"wp-block-paragraph\">Para saber m\u00e1s sobre el arte culinario del foie gras, no olvides <a href=\"https:\/\/relaisgourmet.com\/es\/producto\/cocinar-el-foie-gras\/\">consultar nuestro <strong data-start=\"2936\" data-end=\"2953\">libro electr\u00f3nico <\/strong>titulado <em data-start=\"2963\" data-end=\"2988\">\u00abCocinar el foie gras\u00bb<\/em><\/a>, disponible en nuestro sitio web. Descubrir\u00e1s trucos, consejos y recetas exclusivas para aprovechar al m\u00e1ximo este producto excepcional e impresionar a tus invitados en cada comida.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"261\" src=\"https:\/\/relaisgourmet.com\/wp-content\/uploads\/2021\/12\/image-1-1024x261.png\" alt=\"\" class=\"wp-image-54431\" srcset=\"https:\/\/relaisgourmet.com\/wp-content\/uploads\/2021\/12\/image-1-1024x261.png 1024w, https:\/\/relaisgourmet.com\/wp-content\/uploads\/2021\/12\/image-1-300x76.png 300w, https:\/\/relaisgourmet.com\/wp-content\/uploads\/2021\/12\/image-1-768x196.png 768w, https:\/\/relaisgourmet.com\/wp-content\/uploads\/2021\/12\/image-1-1536x392.png 1536w, https:\/\/relaisgourmet.com\/wp-content\/uploads\/2021\/12\/image-1-600x153.png 600w, https:\/\/relaisgourmet.com\/wp-content\/uploads\/2021\/12\/image-1.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Este plato lleva verduras y foie gras, ofreciendo una experiencia culinaria \u00fanica. El foie gras, ingrediente de lujo por excelencia, se invita a una receta ligera y fresca, perfecta para todas tus ocasiones gourmet. Descubre esta refrescante ensalada que combina verduras crujientes y foie gras entero, una armon\u00eda de sabores para disfrutar con tus invitados. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2562],"tags":[],"class_list":["post-55066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Foie gras con far\u00e1ndula de verduras y frutas<\/title>\n<meta name=\"description\" content=\"Disfruta de una far\u00e1ndula de verduras y frutas con foie gras, ideal para una presentaci\u00f3n original y deliciosa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Farandole de verduras y frutas con Foie Gras\" \/>\n<meta property=\"og:description\" content=\"Disfruta de una far\u00e1ndula de verduras y frutas con foie gras, ideal para una presentaci\u00f3n original y deliciosa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/\" \/>\n<meta property=\"og:site_name\" content=\"Relais Gourmet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/yoast\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-26T05:54:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-12T20:46:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/relaisgourmet.com\/wp-content\/uploads\/2024\/09\/farandole-de-foie-gras.png\" \/>\n\t<meta property=\"og:image:width\" content=\"371\" \/>\n\t<meta property=\"og:image:height\" content=\"442\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/farandole-de-verduras-y-frutas-con-foie-gras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/farandole-de-verduras-y-frutas-con-foie-gras\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Farandole de verduras y frutas con Foie Gras\",\"datePublished\":\"2024-06-26T05:54:45+00:00\",\"dateModified\":\"2025-04-12T20:46:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/farandole-de-verduras-y-frutas-con-foie-gras\\\/\"},\"wordCount\":382,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/farandole-de-verduras-y-frutas-con-foie-gras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/relaisgourmet.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/farandole-de-foie-gras.png\",\"articleSection\":[\"Recetas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/farandole-de-verduras-y-frutas-con-foie-gras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/farandole-de-verduras-y-frutas-con-foie-gras\\\/\",\"url\":\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/farandole-de-verduras-y-frutas-con-foie-gras\\\/\",\"name\":\"Foie gras con far\u00e1ndula de verduras y frutas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/farandole-de-verduras-y-frutas-con-foie-gras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/farandole-de-verduras-y-frutas-con-foie-gras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/relaisgourmet.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/farandole-de-foie-gras.png\",\"datePublished\":\"2024-06-26T05:54:45+00:00\",\"dateModified\":\"2025-04-12T20:46:47+00:00\",\"description\":\"Disfruta de una far\u00e1ndula de verduras y frutas con foie gras, ideal para una presentaci\u00f3n original y deliciosa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/farandole-de-verduras-y-frutas-con-foie-gras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/farandole-de-verduras-y-frutas-con-foie-gras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/farandole-de-verduras-y-frutas-con-foie-gras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/relaisgourmet.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/farandole-de-foie-gras.png\",\"contentUrl\":\"https:\\\/\\\/relaisgourmet.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/farandole-de-foie-gras.png\",\"width\":371,\"height\":442,\"caption\":\"La farandole de l\u00e9gumes et fruits avec Foie Gras\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/farandole-de-verduras-y-frutas-con-foie-gras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/https-relaisgourmet-com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Farandole de verduras y frutas con Foie Gras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/#website\",\"url\":\"https:\\\/\\\/relaisgourmet.com\\\/\",\"name\":\"Relais Gourmet\",\"description\":\"Maison Gastronomique au Pays-Basque Depuis 2004\",\"publisher\":{\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/relaisgourmet.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/#organization\",\"name\":\"Relais Gourmet\",\"url\":\"https:\\\/\\\/relaisgourmet.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/relaisgourmet.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Diseno-sin-titulo-8.jpg\",\"contentUrl\":\"https:\\\/\\\/relaisgourmet.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Diseno-sin-titulo-8.jpg\",\"width\":500,\"height\":500,\"caption\":\"Relais Gourmet\"},\"image\":{\"@id\":\"https:\\\/\\\/relaisgourmet.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/yoast\",\"https:\\\/\\\/instagram.com\\\/yoast\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/relaisgourmet.com\\\/es\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Foie gras con far\u00e1ndula de verduras y frutas","description":"Disfruta de una far\u00e1ndula de verduras y frutas con foie gras, ideal para una presentaci\u00f3n original y deliciosa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/","og_locale":"es_ES","og_type":"article","og_title":"Farandole de verduras y frutas con Foie Gras","og_description":"Disfruta de una far\u00e1ndula de verduras y frutas con foie gras, ideal para una presentaci\u00f3n original y deliciosa.","og_url":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/","og_site_name":"Relais Gourmet","article_publisher":"https:\/\/facebook.com\/yoast","article_published_time":"2024-06-26T05:54:45+00:00","article_modified_time":"2025-04-12T20:46:47+00:00","og_image":[{"width":371,"height":442,"url":"https:\/\/relaisgourmet.com\/wp-content\/uploads\/2024\/09\/farandole-de-foie-gras.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/#article","isPartOf":{"@id":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/"},"author":{"name":"","@id":""},"headline":"Farandole de verduras y frutas con Foie Gras","datePublished":"2024-06-26T05:54:45+00:00","dateModified":"2025-04-12T20:46:47+00:00","mainEntityOfPage":{"@id":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/"},"wordCount":382,"commentCount":0,"publisher":{"@id":"https:\/\/relaisgourmet.com\/#organization"},"image":{"@id":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/#primaryimage"},"thumbnailUrl":"https:\/\/relaisgourmet.com\/wp-content\/uploads\/2024\/09\/farandole-de-foie-gras.png","articleSection":["Recetas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/","url":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/","name":"Foie gras con far\u00e1ndula de verduras y frutas","isPartOf":{"@id":"https:\/\/relaisgourmet.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/#primaryimage"},"image":{"@id":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/#primaryimage"},"thumbnailUrl":"https:\/\/relaisgourmet.com\/wp-content\/uploads\/2024\/09\/farandole-de-foie-gras.png","datePublished":"2024-06-26T05:54:45+00:00","dateModified":"2025-04-12T20:46:47+00:00","description":"Disfruta de una far\u00e1ndula de verduras y frutas con foie gras, ideal para una presentaci\u00f3n original y deliciosa.","breadcrumb":{"@id":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/#primaryimage","url":"https:\/\/relaisgourmet.com\/wp-content\/uploads\/2024\/09\/farandole-de-foie-gras.png","contentUrl":"https:\/\/relaisgourmet.com\/wp-content\/uploads\/2024\/09\/farandole-de-foie-gras.png","width":371,"height":442,"caption":"La farandole de l\u00e9gumes et fruits avec Foie Gras"},{"@type":"BreadcrumbList","@id":"https:\/\/relaisgourmet.com\/es\/farandole-de-verduras-y-frutas-con-foie-gras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/relaisgourmet.com\/es\/https-relaisgourmet-com\/"},{"@type":"ListItem","position":2,"name":"Farandole de verduras y frutas con Foie Gras"}]},{"@type":"WebSite","@id":"https:\/\/relaisgourmet.com\/#website","url":"https:\/\/relaisgourmet.com\/","name":"Relais Gourmet","description":"Maison Gastronomique au Pays-Basque Depuis 2004","publisher":{"@id":"https:\/\/relaisgourmet.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/relaisgourmet.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/relaisgourmet.com\/#organization","name":"Relais Gourmet","url":"https:\/\/relaisgourmet.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/relaisgourmet.com\/#\/schema\/logo\/image\/","url":"https:\/\/relaisgourmet.com\/wp-content\/uploads\/2024\/11\/Diseno-sin-titulo-8.jpg","contentUrl":"https:\/\/relaisgourmet.com\/wp-content\/uploads\/2024\/11\/Diseno-sin-titulo-8.jpg","width":500,"height":500,"caption":"Relais Gourmet"},"image":{"@id":"https:\/\/relaisgourmet.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/yoast","https:\/\/instagram.com\/yoast"]},{"@type":"Person","@id":"","url":"https:\/\/relaisgourmet.com\/es\/author\/"}]}},"jetpack_featured_media_url":"https:\/\/relaisgourmet.com\/wp-content\/uploads\/2024\/09\/farandole-de-foie-gras.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/relaisgourmet.com\/es\/wp-json\/wp\/v2\/posts\/55066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/relaisgourmet.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/relaisgourmet.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/relaisgourmet.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/relaisgourmet.com\/es\/wp-json\/wp\/v2\/comments?post=55066"}],"version-history":[{"count":0,"href":"https:\/\/relaisgourmet.com\/es\/wp-json\/wp\/v2\/posts\/55066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/relaisgourmet.com\/es\/wp-json\/wp\/v2\/media\/37625"}],"wp:attachment":[{"href":"https:\/\/relaisgourmet.com\/es\/wp-json\/wp\/v2\/media?parent=55066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/relaisgourmet.com\/es\/wp-json\/wp\/v2\/categories?post=55066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/relaisgourmet.com\/es\/wp-json\/wp\/v2\/tags?post=55066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}